{"id":3937,"date":"2018-06-08T00:00:00","date_gmt":"2018-06-07T22:00:00","guid":{"rendered":"https:\/\/felios-new.cg-dev.eu\/collection\/o-alexandros-ke-o-drakos\/"},"modified":"2019-04-01T10:40:36","modified_gmt":"2019-04-01T08:40:36","slug":"o-alexandros-ke-o-drakos","status":"publish","type":"collection","link":"https:\/\/felioscollection.gr\/el\/collection\/o-alexandros-ke-o-drakos\/","title":{"rendered":"\u039f \u0391\u03bb\u03ad\u03be\u03b1\u03bd\u03b4\u03c1\u03bf\u03c2 \u03ba\u03b1\u03b9 \u03bf \u03b4\u03c1\u03ac\u03ba\u03bf\u03c2"},"content":{"rendered":"","protected":false},"featured_media":6961,"parent":0,"template":"","acf":[],"_links":{"self":[{"href":"https:\/\/felioscollection.gr\/el\/wp-json\/wp\/v2\/collection\/3937\/"}],"collection":[{"href":"https:\/\/felioscollection.gr\/el\/wp-json\/wp\/v2\/collection\/"}],"about":[{"href":"https:\/\/felioscollection.gr\/el\/wp-json\/wp\/v2\/types\/collection\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/felioscollection.gr\/el\/wp-json\/wp\/v2\/media\/6961\/"}],"wp:attachment":[{"href":"https:\/\/felioscollection.gr\/el\/wp-json\/wp\/v2\/media\/?parent=3937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}